{"id":1519,"date":"2011-10-10T08:42:43","date_gmt":"2011-10-10T06:42:43","guid":{"rendered":"http:\/\/www.spa-balance.com\/?p=843"},"modified":"2011-10-10T08:42:43","modified_gmt":"2011-10-10T06:42:43","slug":"estrategias-correctivas-para-los-centros-en-crisis-parte-10-el-rol-del-consultor","status":"publish","type":"post","link":"http:\/\/www.spa-balance.com\/es\/2011\/10\/estrategias-correctivas-para-los-centros-en-crisis-parte-10-el-rol-del-consultor\/","title":{"rendered":"Estrategias Correctivas para los Spas en Crisis &#8211; Parte 10: El rol del consultor (Espa\u00f1ol)"},"content":{"rendered":"<p><!--:es--><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: left;\">Despu\u00e9s de nueve entradas sobre centros en crisis queremos cerrar este ciclo explicando el importante rol del consultor para convertir un negocio en crisis en un centro con \u00e9xito. Bien hablamos durante estas semanas sobre diversos temas, problemas, estrategias y soluciones pero quer\u00edamos dejar para el \u00faltimo post \u201cla esencia\u201d de cada soluci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: left;\">Como vimos en el <a title=\"Estrategias Correctivas para los Centros en Crisis\" href=\"http:\/\/www.spa-balance.com\/es\/2011\/07\/02\/estrategias-correctivas-para-los-centros-en-crisis\/\">primer art\u00edculo sobre centros en crisis<\/a>, el sector del spa, por su excepcional crecimiento hab\u00eda atra\u00eddo muchos inversores y empresarios en los \u00faltimos a\u00f1os. Muchos proyectos quedaron en el camino, y muchos negocios cerraron por falta de conocimientos del sector y una clara estrategia del negocio. Aunque vivimos en un mundo donde nos bombardean con informaci\u00f3n y se puede obtener informaci\u00f3n por todos lados no debemos olvidarnos de lo siguiente: para que un negocio marche bien, no es suficiente sacar informaci\u00f3n de varios fuentes e intentar aplicarlo al propio negocio. \u201cHacer parches\u201d puede dar resultados a corto plazo, pero para alcanzar el \u00e9xito a largo plazo es necesario tener un gui\u00f3n bien pensado y bien escrito. Y para poder escribir bien ese gui\u00f3n es importante contar con la experiencia y el\u00a0<em>know how<\/em> de un experto como es el caso del consultor. Hay que tener claro desde el principio que consultar un experto no es un <em>sin ti<\/em> sino un <em>contigo<\/em>. El consultor ofrece objetividad, analizando cada aspecto del negocio para poder ofrecer una visi\u00f3n clara y proponer estrategias de soluci\u00f3n. Esta soluci\u00f3n, dependiendo de cada caso, puede ser distinta.\u00a0 Un consultor puede optimizar el funcionamiento de un negocio con servicios puntuales, como son la optimizaci\u00f3n de ingresos, la auditoria operacional o cursos de formaci\u00f3n, o con servicios a largo plazo como son la gesti\u00f3n o la gesti\u00f3n guiada, entre otros.<\/p>\n<p style=\"text-align: left;\"><!--:--><!--more--><!--:es--><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: left;\"><strong><a title=\"Optimizaci\u00f3n de Ingresos\" href=\"http:\/\/www.spa-balance.com\/es\/servicios\/optimizacion-de-ingresos\/\" target=\"_blank\" rel=\"noopener\">Optimizaci\u00f3n de ingresos<\/a>\/ Auditoria operacional\/ La gesti\u00f3n guiada<\/strong><\/p>\n<p style=\"text-align: left;\">La auditoria operacional consiste en un an\u00e1lisis detallado de todos los aspectos claves del negocio, que en caso de Spa Balance es interno y externo. Despu\u00e9s de la auditoria se prepara un informe con las principales carencias del negocio. Spa Balance ofrece, a parte del informe las estrategias correctivas que deben implementarse para un funcionamiento \u00f3ptimo. En caso de no tener recursos o tiempo para aplicarlas los expertos pueden prestar asistencia en aplicarlos. La auditoria es de gran ayuda para todas las empresas, no solamente para negocios en crisis. En caso de los negocios exitosos la auditoria puede resultar una herramienta \u00fatil para poder mantener la calidad a largo plazo y para los centros con problemas les ofrece una visi\u00f3n global de los problemas del negocio, ense\u00f1ando los fallos y ofreciendo estrategias de soluci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: left;\">Mientras la gesti\u00f3n guiada es un seguimiento a largo plazo, de entre 2-3 a\u00f1os, que ofrece una soluci\u00f3n polifac\u00e9tica a un coste asequible. No solamente fija los est\u00e1ndares de rendimiento sino\u00a0 tambi\u00e9n supervisa la ejecuci\u00f3n de la operaci\u00f3n t\u00e9cnica del spa y pone a disposici\u00f3n del spa la pericia necesaria que muy pocas veces tiene un director del spa. La finalidad de la gesti\u00f3n guiada es hacer el spa econ\u00f3micamente viable con la ayuda del consultor.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: left;\"><strong>\u00bfPor qu\u00e9 contratar un consultor?<\/strong><\/p>\n<p style=\"text-align: left;\">La importancia de contar con expertos es algo que hab\u00eda sido infravalorado en los \u00faltimos tiempos. Aunque haya una \u201csobredosis\u201d de informaci\u00f3n en el mercado, gestionar un negocio no es cuesti\u00f3n de hacer puzles de trozos de informaci\u00f3n, aplicando adem\u00e1s novedades y tendencias. No es suficiente tener la informaci\u00f3n, hay que saber <em>interpretarla<\/em> y <em>aplicarla<\/em>. Esta es la aportaci\u00f3n del consultor: conocimientos profundos del sector, experiencia, <em>know how<\/em>, y objetividad. No debemos olvidarnos de que para tener \u00e9xito en este sector de crecimiento r\u00e1pido y muy competidor, conocer al fondo las peculiaridades de la industria en cuesti\u00f3n es fundamental. \u00a0La \u00fanica manera de conseguir ese conocimiento del sector es estando en el. Es donde empieza el gui\u00f3n de cada negocio. Y el consultor es la gu\u00eda perfecta.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: left;\">Durante diez posts les hablamos de las estrategias correctivas para centros en crisis, enfocando diferentes problemas, intentando dar una informaci\u00f3n \u00fatil para los profesionales del sector. Han sido posts diferentes, con enfoques diferentes, pero siempre con la misma ilusi\u00f3n de informar y compartir conocimiento. Esperamos que estos posts les hayan servido de ayuda para saber c\u00f3mo enfocar los posibles problemas y saber c\u00f3mo y d\u00f3nde encontrar soluci\u00f3n. Por nuestra parte ha sido un viaje interesante y enriquecedor, esperamos haber sido buenos compa\u00f1eros del viaje. Por \u00faltimo quisi\u00e9ramos conocer su opini\u00f3n sobre nuestros art\u00edculos. Si tienen preguntas o comentarios respecto a nuestros art\u00edculos no duden en ponerse en contacto con nosotros, bien comentando los posts o enviando un email a nuestra direcci\u00f3n: <a href=\"mailto:info@spa-balance.com\">info@spa-balance.com<\/a>.<\/p>\n<p><!--:--><\/p>","protected":false},"excerpt":{"rendered":"<p>&nbsp; Despu\u00e9s de nueve entradas sobre centros en crisis queremos cerrar este ciclo explicando el importante rol del consultor para convertir un negocio en crisis en un centro con \u00e9xito. Bien hablamos durante estas semanas sobre diversos temas, problemas, estrategias y soluciones pero quer\u00edamos dejar para el \u00faltimo post \u201cla esencia\u201d de cada soluci\u00f3n. &nbsp; [&hellip;]<\/p>","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[9,10],"tags":[4,5,6,95,31,8,97,11],"class_list":["post-1519","post","type-post","status-publish","format-standard","hentry","category-spa-management-2","category-spa-revenue-management-2","tag-asesores-de-centros-de-belleza","tag-asesores-de-spas","tag-centros-de-belleza-en-crisis","tag-consultoria-spas","tag-formacion-de-spas","tag-gestion-de-spas","tag-spa-consulting","tag-spas-en-crisis"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Estrategias Correctivas para los Spas en Crisis - Parte 10: El rol del consultor (Espa\u00f1ol) &#8212; Spa Balance<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.spa-balance.com\/es\/2011\/10\/estrategias-correctivas-para-los-centros-en-crisis-parte-10-el-rol-del-consultor\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estrategias Correctivas para los Spas en Crisis - Parte 10: El rol del consultor (Espa\u00f1ol) &#8212; Spa Balance\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Despu\u00e9s de nueve entradas sobre centros en crisis queremos cerrar este ciclo explicando el importante rol del consultor para convertir un negocio en crisis en un centro con \u00e9xito. Bien hablamos durante estas semanas sobre diversos temas, problemas, estrategias y soluciones pero quer\u00edamos dejar para el \u00faltimo post \u201cla esencia\u201d de cada soluci\u00f3n. &nbsp; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.spa-balance.com\/es\/2011\/10\/estrategias-correctivas-para-los-centros-en-crisis-parte-10-el-rol-del-consultor\/\" \/>\n<meta property=\"og:site_name\" content=\"Spa Balance\" \/>\n<meta property=\"article:published_time\" content=\"2011-10-10T06:42:43+00:00\" \/>\n<meta name=\"author\" content=\"Sonal Uberoi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sonal Uberoi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.spa-balance.com\\\/2011\\\/10\\\/estrategias-correctivas-para-los-centros-en-crisis-parte-10-el-rol-del-consultor\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.spa-balance.com\\\/2011\\\/10\\\/estrategias-correctivas-para-los-centros-en-crisis-parte-10-el-rol-del-consultor\\\/\"},\"author\":{\"name\":\"Sonal Uberoi\",\"@id\":\"https:\\\/\\\/www.spa-balance.com\\\/#\\\/schema\\\/person\\\/8e140ef4f1a16322c5ef0d258647f8b3\"},\"headline\":\"Estrategias Correctivas para los Spas en Crisis &#8211; Parte 10: El rol del consultor (Espa\u00f1ol)\",\"datePublished\":\"2011-10-10T06:42:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.spa-balance.com\\\/2011\\\/10\\\/estrategias-correctivas-para-los-centros-en-crisis-parte-10-el-rol-del-consultor\\\/\"},\"wordCount\":844,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.spa-balance.com\\\/#organization\"},\"keywords\":[\"Asesores de centros de belleza\",\"Asesores de spas\",\"Centros de Belleza en Crisis\",\"consultor\u00eda spas\",\"Formaci\u00f3n de spas\",\"Gesti\u00f3n de spas\",\"spa consulting\",\"Spas en Crisis\"],\"articleSection\":[\"Spa Management\",\"Spa Revenue Optimisation\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.spa-balance.com\\\/2011\\\/10\\\/estrategias-correctivas-para-los-centros-en-crisis-parte-10-el-rol-del-consultor\\\/\",\"url\":\"https:\\\/\\\/www.spa-balance.com\\\/2011\\\/10\\\/estrategias-correctivas-para-los-centros-en-crisis-parte-10-el-rol-del-consultor\\\/\",\"name\":\"Estrategias Correctivas para los Spas en Crisis - Parte 10: El rol del consultor (Espa\u00f1ol) &#8212; Spa Balance\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.spa-balance.com\\\/#website\"},\"datePublished\":\"2011-10-10T06:42:43+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.spa-balance.com\\\/2011\\\/10\\\/estrategias-correctivas-para-los-centros-en-crisis-parte-10-el-rol-del-consultor\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.spa-balance.com\\\/#website\",\"url\":\"https:\\\/\\\/www.spa-balance.com\\\/\",\"name\":\"Spa Balance\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.spa-balance.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.spa-balance.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.spa-balance.com\\\/#organization\",\"name\":\"Spa Balance Consulting\",\"url\":\"https:\\\/\\\/www.spa-balance.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.spa-balance.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.spa-balance.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.spa-balance.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/logo.png\",\"width\":209,\"height\":75,\"caption\":\"Spa Balance Consulting\"},\"image\":{\"@id\":\"https:\\\/\\\/www.spa-balance.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.spa-balance.com\\\/#\\\/schema\\\/person\\\/8e140ef4f1a16322c5ef0d258647f8b3\",\"name\":\"Sonal Uberoi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/www.spa-balance.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/902B1583-cropped.jpg?fit=96%2C96&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.spa-balance.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/902B1583-cropped.jpg?fit=96%2C96&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.spa-balance.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/902B1583-cropped.jpg?fit=96%2C96&ssl=1\",\"caption\":\"Sonal Uberoi\"},\"url\":\"http:\\\/\\\/www.spa-balance.com\\\/es\\\/author\\\/sonal\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estrategias Correctivas para los Spas en Crisis - Parte 10: El rol del consultor (Espa\u00f1ol) &#8212; Spa Balance","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.spa-balance.com\/es\/2011\/10\/estrategias-correctivas-para-los-centros-en-crisis-parte-10-el-rol-del-consultor\/","og_locale":"es_ES","og_type":"article","og_title":"Estrategias Correctivas para los Spas en Crisis - Parte 10: El rol del consultor (Espa\u00f1ol) &#8212; Spa Balance","og_description":"&nbsp; Despu\u00e9s de nueve entradas sobre centros en crisis queremos cerrar este ciclo explicando el importante rol del consultor para convertir un negocio en crisis en un centro con \u00e9xito. Bien hablamos durante estas semanas sobre diversos temas, problemas, estrategias y soluciones pero quer\u00edamos dejar para el \u00faltimo post \u201cla esencia\u201d de cada soluci\u00f3n. &nbsp; [&hellip;]","og_url":"https:\/\/www.spa-balance.com\/es\/2011\/10\/estrategias-correctivas-para-los-centros-en-crisis-parte-10-el-rol-del-consultor\/","og_site_name":"Spa Balance","article_published_time":"2011-10-10T06:42:43+00:00","author":"Sonal Uberoi","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Sonal Uberoi","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.spa-balance.com\/2011\/10\/estrategias-correctivas-para-los-centros-en-crisis-parte-10-el-rol-del-consultor\/#article","isPartOf":{"@id":"https:\/\/www.spa-balance.com\/2011\/10\/estrategias-correctivas-para-los-centros-en-crisis-parte-10-el-rol-del-consultor\/"},"author":{"name":"Sonal Uberoi","@id":"https:\/\/www.spa-balance.com\/#\/schema\/person\/8e140ef4f1a16322c5ef0d258647f8b3"},"headline":"Estrategias Correctivas para los Spas en Crisis &#8211; Parte 10: El rol del consultor (Espa\u00f1ol)","datePublished":"2011-10-10T06:42:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.spa-balance.com\/2011\/10\/estrategias-correctivas-para-los-centros-en-crisis-parte-10-el-rol-del-consultor\/"},"wordCount":844,"commentCount":0,"publisher":{"@id":"https:\/\/www.spa-balance.com\/#organization"},"keywords":["Asesores de centros de belleza","Asesores de spas","Centros de Belleza en Crisis","consultor\u00eda spas","Formaci\u00f3n de spas","Gesti\u00f3n de spas","spa consulting","Spas en Crisis"],"articleSection":["Spa Management","Spa Revenue Optimisation"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.spa-balance.com\/2011\/10\/estrategias-correctivas-para-los-centros-en-crisis-parte-10-el-rol-del-consultor\/","url":"https:\/\/www.spa-balance.com\/2011\/10\/estrategias-correctivas-para-los-centros-en-crisis-parte-10-el-rol-del-consultor\/","name":"Estrategias Correctivas para los Spas en Crisis - Parte 10: El rol del consultor (Espa\u00f1ol) &#8212; Spa Balance","isPartOf":{"@id":"https:\/\/www.spa-balance.com\/#website"},"datePublished":"2011-10-10T06:42:43+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.spa-balance.com\/2011\/10\/estrategias-correctivas-para-los-centros-en-crisis-parte-10-el-rol-del-consultor\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.spa-balance.com\/#website","url":"https:\/\/www.spa-balance.com\/","name":"Spa Balance","description":"","publisher":{"@id":"https:\/\/www.spa-balance.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.spa-balance.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.spa-balance.com\/#organization","name":"Spa Balance Consulting","url":"https:\/\/www.spa-balance.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.spa-balance.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.spa-balance.com\/wp-content\/uploads\/2021\/03\/logo.png","contentUrl":"https:\/\/www.spa-balance.com\/wp-content\/uploads\/2021\/03\/logo.png","width":209,"height":75,"caption":"Spa Balance Consulting"},"image":{"@id":"https:\/\/www.spa-balance.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.spa-balance.com\/#\/schema\/person\/8e140ef4f1a16322c5ef0d258647f8b3","name":"Sonal Uberoi","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/i0.wp.com\/www.spa-balance.com\/wp-content\/uploads\/2021\/03\/902B1583-cropped.jpg?fit=96%2C96&ssl=1","url":"https:\/\/i0.wp.com\/www.spa-balance.com\/wp-content\/uploads\/2021\/03\/902B1583-cropped.jpg?fit=96%2C96&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.spa-balance.com\/wp-content\/uploads\/2021\/03\/902B1583-cropped.jpg?fit=96%2C96&ssl=1","caption":"Sonal Uberoi"},"url":"http:\/\/www.spa-balance.com\/es\/author\/sonal\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/www.spa-balance.com\/es\/wp-json\/wp\/v2\/posts\/1519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.spa-balance.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.spa-balance.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.spa-balance.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.spa-balance.com\/es\/wp-json\/wp\/v2\/comments?post=1519"}],"version-history":[{"count":0,"href":"http:\/\/www.spa-balance.com\/es\/wp-json\/wp\/v2\/posts\/1519\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.spa-balance.com\/es\/wp-json\/wp\/v2\/media?parent=1519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.spa-balance.com\/es\/wp-json\/wp\/v2\/categories?post=1519"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.spa-balance.com\/es\/wp-json\/wp\/v2\/tags?post=1519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}